{"id":1220,"date":"2023-09-11T08:00:37","date_gmt":"2023-09-11T06:00:37","guid":{"rendered":"https:\/\/juliette-cortese.fr\/?p=1220"},"modified":"2023-09-11T15:06:24","modified_gmt":"2023-09-11T13:06:24","slug":"42-aout-2","status":"publish","type":"post","link":"https:\/\/juliette-cortese.fr\/index.php\/2023\/09\/11\/42-aout-2\/","title":{"rendered":"42 ao\u00fbt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Escaliers des ombres et pieds de poussi\u00e8re. J&rsquo;ai oubli\u00e9 mes jambes de femme, elles ne sont plus emprunt ni greffe, ni une transformation opportuniste du bas. Elles sont l\u00e0, me prolongent le corps, marchent debout et me transportent en bip\u00e8de ordinaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est une chose au moins, de gu\u00e9rie. Quoiqu&rsquo;inexpliqu\u00e9e.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je ne me rends pas heureux pour autant. Le bonheur est d&rsquo;un autre prix, que je ne cherche pas \u00e0 payer. Je voudrais seulement savoir, ce qui me co\u00fbte tant.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escaliers des ombres et pieds de poussi\u00e8re. J&rsquo;ai oubli\u00e9 mes jambes de femme, elles ne sont plus emprunt ni greffe, ni une transformation opportuniste du bas. Elles sont l\u00e0, me prolongent le corps, marchent debout et me transportent en bip\u00e8de ordinaire. C&rsquo;est une chose au moins, de gu\u00e9rie. Quoiqu&rsquo;inexpliqu\u00e9e.\u00a0 Je ne me rends pas heureux [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-1220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-91eme-parallele"],"_links":{"self":[{"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/posts\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":2,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/posts\/1220\/revisions"}],"predecessor-version":[{"id":1271,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/posts\/1220\/revisions\/1271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/media\/1219"}],"wp:attachment":[{"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/juliette-cortese.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}